{"id":108,"count":4,"description":"","link":"https:\/\/box28store.com\/es\/categoria-producto\/adidas\/adidas-spezial\/","name":"Adidas Spezial","slug":"adidas-spezial","taxonomy":"product_cat","parent":19,"meta":[],"menu_order":2,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adidas Spezial Archives - Box 28Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/box28store.com\/es\/categoria-producto\/adidas\/adidas-spezial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adidas Spezial Archives - Box 28Store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/box28store.com\/es\/categoria-producto\/adidas\/adidas-spezial\/\" \/>\n<meta property=\"og:site_name\" content=\"Box 28Store\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/box28store.com\\\/categoria-produto\\\/adidas\\\/adidas-spezial\\\/\",\"url\":\"https:\\\/\\\/box28store.com\\\/categoria-produto\\\/adidas\\\/adidas-spezial\\\/\",\"name\":\"Adidas Spezial Archives - Box 28Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/box28store.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/box28store.com\\\/categoria-produto\\\/adidas\\\/adidas-spezial\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/box28store.com\\\/categoria-produto\\\/adidas\\\/adidas-spezial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/box28store.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adidas\",\"item\":\"https:\\\/\\\/box28store.com\\\/categoria-produto\\\/adidas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adidas Spezial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/box28store.com\\\/#website\",\"url\":\"https:\\\/\\\/box28store.com\\\/\",\"name\":\"Box 28Store\",\"description\":\"Loja online de sapatilhas para homem e mulher. Adidas, Nike, New Balance, Puma e muito mais. Envios r\u00e1pidos para Portugal.\",\"publisher\":{\"@id\":\"https:\\\/\\\/box28store.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/box28store.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/box28store.com\\\/#organization\",\"name\":\"Box 28Store\",\"url\":\"https:\\\/\\\/box28store.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/box28store.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/box28store.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-LOGOBOX28STORE-1.png\",\"contentUrl\":\"https:\\\/\\\/box28store.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-LOGOBOX28STORE-1.png\",\"width\":453,\"height\":122,\"caption\":\"Box 28Store\"},\"image\":{\"@id\":\"https:\\\/\\\/box28store.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adidas Spezial Archives - Box 28Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/box28store.com\/es\/categoria-producto\/adidas\/adidas-spezial\/","og_locale":"es_ES","og_type":"article","og_title":"Adidas Spezial Archives - Box 28Store","og_url":"https:\/\/box28store.com\/es\/categoria-producto\/adidas\/adidas-spezial\/","og_site_name":"Box 28Store","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/box28store.com\/categoria-produto\/adidas\/adidas-spezial\/","url":"https:\/\/box28store.com\/categoria-produto\/adidas\/adidas-spezial\/","name":"Adidas Spezial Archives - Box 28Store","isPartOf":{"@id":"https:\/\/box28store.com\/#website"},"breadcrumb":{"@id":"https:\/\/box28store.com\/categoria-produto\/adidas\/adidas-spezial\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/box28store.com\/categoria-produto\/adidas\/adidas-spezial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/box28store.com\/"},{"@type":"ListItem","position":2,"name":"Adidas","item":"https:\/\/box28store.com\/categoria-produto\/adidas\/"},{"@type":"ListItem","position":3,"name":"Adidas Spezial"}]},{"@type":"WebSite","@id":"https:\/\/box28store.com\/#website","url":"https:\/\/box28store.com\/","name":"Box 28Store","description":"Loja online de sapatilhas para homem e mulher. Adidas, Nike, New Balance, Puma e muito mais. Envios r\u00e1pidos para Portugal.","publisher":{"@id":"https:\/\/box28store.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/box28store.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/box28store.com\/#organization","name":"Box 28Store","url":"https:\/\/box28store.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/box28store.com\/#\/schema\/logo\/image\/","url":"https:\/\/box28store.com\/wp-content\/uploads\/2024\/02\/cropped-LOGOBOX28STORE-1.png","contentUrl":"https:\/\/box28store.com\/wp-content\/uploads\/2024\/02\/cropped-LOGOBOX28STORE-1.png","width":453,"height":122,"caption":"Box 28Store"},"image":{"@id":"https:\/\/box28store.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/box28store.com\/es\/wp-json\/wp\/v2\/product_cat\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/box28store.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/box28store.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/box28store.com\/es\/wp-json\/wp\/v2\/product_cat\/19"}],"wp:post_type":[{"href":"https:\/\/box28store.com\/es\/wp-json\/wp\/v2\/product?product_cat=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}